{"id":173,"count":6,"description":"","link":"https:\/\/www.passele.com\/cs\/topics\/tipy-na-odstraneni-hesla-zip\/","name":"Tipy na odstran\u011bn\u00ed hesla ZIP","slug":"tipy-na-odstraneni-hesla-zip","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tipy na odstran\u011bn\u00ed hesla ZIP - Passele<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.passele.com\/cs\/topics\/tipy-na-odstraneni-hesla-zip\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tipy na odstran\u011bn\u00ed hesla ZIP - Passele\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.passele.com\/cs\/topics\/tipy-na-odstraneni-hesla-zip\/\" \/>\n<meta property=\"og:site_name\" content=\"Passele\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.passele.com\/cs\/topics\/tipy-na-odstraneni-hesla-zip\/\",\"url\":\"https:\/\/www.passele.com\/cs\/topics\/tipy-na-odstraneni-hesla-zip\/\",\"name\":\"Tipy na odstran\u011bn\u00ed hesla ZIP - Passele\",\"isPartOf\":{\"@id\":\"https:\/\/www.passele.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.passele.com\/cs\/topics\/tipy-na-odstraneni-hesla-zip\/#breadcrumb\"},\"inLanguage\":\"cs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.passele.com\/cs\/topics\/tipy-na-odstraneni-hesla-zip\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9801\",\"item\":\"https:\/\/www.passele.com\/cs\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tipy na odstran\u011bn\u00ed hesla ZIP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.passele.com\/#website\",\"url\":\"https:\/\/www.passele.com\/\",\"name\":\"Passele\",\"description\":\"Powerful and Professional File Password Removal Tools\",\"publisher\":{\"@id\":\"https:\/\/www.passele.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.passele.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.passele.com\/#organization\",\"name\":\"Passele\",\"url\":\"https:\/\/www.passele.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\/\/www.passele.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.passele.com\/images\/passele-icon.png\",\"contentUrl\":\"https:\/\/www.passele.com\/images\/passele-icon.png\",\"width\":64,\"height\":64,\"caption\":\"Passele\"},\"image\":{\"@id\":\"https:\/\/www.passele.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tipy na odstran\u011bn\u00ed hesla ZIP - Passele","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.passele.com\/cs\/topics\/tipy-na-odstraneni-hesla-zip\/","og_locale":"cs_CZ","og_type":"article","og_title":"Tipy na odstran\u011bn\u00ed hesla ZIP - Passele","og_url":"https:\/\/www.passele.com\/cs\/topics\/tipy-na-odstraneni-hesla-zip\/","og_site_name":"Passele","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.passele.com\/cs\/topics\/tipy-na-odstraneni-hesla-zip\/","url":"https:\/\/www.passele.com\/cs\/topics\/tipy-na-odstraneni-hesla-zip\/","name":"Tipy na odstran\u011bn\u00ed hesla ZIP - Passele","isPartOf":{"@id":"https:\/\/www.passele.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.passele.com\/cs\/topics\/tipy-na-odstraneni-hesla-zip\/#breadcrumb"},"inLanguage":"cs"},{"@type":"BreadcrumbList","@id":"https:\/\/www.passele.com\/cs\/topics\/tipy-na-odstraneni-hesla-zip\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9801","item":"https:\/\/www.passele.com\/cs\/"},{"@type":"ListItem","position":2,"name":"Tipy na odstran\u011bn\u00ed hesla ZIP"}]},{"@type":"WebSite","@id":"https:\/\/www.passele.com\/#website","url":"https:\/\/www.passele.com\/","name":"Passele","description":"Powerful and Professional File Password Removal Tools","publisher":{"@id":"https:\/\/www.passele.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.passele.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/www.passele.com\/#organization","name":"Passele","url":"https:\/\/www.passele.com\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/www.passele.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.passele.com\/images\/passele-icon.png","contentUrl":"https:\/\/www.passele.com\/images\/passele-icon.png","width":64,"height":64,"caption":"Passele"},"image":{"@id":"https:\/\/www.passele.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.passele.com\/cs\/wp-json\/wp\/v2\/categories\/173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.passele.com\/cs\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.passele.com\/cs\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.passele.com\/cs\/wp-json\/wp\/v2\/posts?categories=173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}