{"id":27411,"date":"2022-06-10T09:29:09","date_gmt":"2022-06-10T09:29:09","guid":{"rendered":"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/"},"modified":"2022-06-10T09:29:09","modified_gmt":"2022-06-10T09:29:09","slug":"%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5","status":"publish","type":"post","link":"https:\/\/www.passele.com\/th\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/","title":{"rendered":"\u0e27\u0e34\u0e18\u0e35\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e25\u0e37\u0e21"},"content":{"rendered":"<p>\u0e2a\u0e34\u0e48\u0e07\u0e19\u0e35\u0e49\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e01\u0e31\u0e1a\u0e1e\u0e27\u0e01\u0e40\u0e23\u0e32\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19! \u0e04\u0e38\u0e13\u0e19\u0e31\u0e48\u0e07\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e25\u0e07\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e43\u0e0a\u0e49\u0e1a\u0e31\u0e0d\u0e0a\u0e35 Windows 11 \u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e49\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e25\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e07\u0e2a\u0e31\u0e1a\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e2a\u0e21\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e41\u0e1a\u0e1a\u0e41\u0e25\u0e49\u0e27 \u0e01\u0e47\u0e44\u0e21\u0e48\u0e21\u0e35\u0e17\u0e32\u0e07\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e41\u0e25\u0e30\u0e04\u0e38\u0e13\u0e22\u0e31\u0e07\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49 \u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e04\u0e34\u0e14\u0e01\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e27\u0e48\u0e32 <em>\u201c\u0e09\u0e31\u0e19\u0e04\u0e27\u0e23\u0e17\u0e33\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23? \u0e09\u0e31\u0e19\u0e25\u0e37\u0e21\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19\u201d<\/em> \u0e19\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e40\u0e27\u0e25\u0e32\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e08\u0e30\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e08\u0e4b\u0e07\u0e40\u0e1e\u0e23\u0e32\u0e30 <strong>\u0e01\u0e32\u0e23\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e25\u0e37\u0e21\u0e44\u0e1b\u0e19\u0e31\u0e49\u0e19\u0e07\u0e48\u0e32\u0e22\u0e40\u0e01\u0e34\u0e19\u0e44\u0e1b<\/strong> \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e44\u0e14\u0e49\u0e43\u0e19\u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e07\u0e48\u0e32\u0e22\u0e46<\/p>\n<p>\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e0a\u0e48\u0e27\u0e22\u0e04\u0e38\u0e13\u0e44\u0e14\u0e49\u0e43\u0e19\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e40\u0e2b\u0e15\u0e38\u0e43\u0e14\u0e09\u0e31\u0e19\u0e08\u0e36\u0e07\u0e25\u0e37\u0e21\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11<\/p>\n<h3>\u0e27\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48 1 \u0e27\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e25\u0e37\u0e21\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e2d\u0e30\u0e44\u0e23\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19<\/h3>\n<p><a href=\"https:\/\/www.passele.com\/go\/win-password-recovery\" target=\"_blank\" rel=\"noopener\">Windows Password Remover<\/a> \u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e25\u0e37\u0e21\u0e43\u0e19\u0e1b\u0e35 2022 \u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11\/10 \u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows \u0e14\u0e49\u0e27\u0e22\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22 \u0e04\u0e38\u0e13\u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e17\u0e32\u0e07\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c\u0e19\u0e35\u0e49 \u0e41\u0e25\u0e30\u0e04\u0e38\u0e13\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e41\u0e1b\u0e25\u0e01\u0e43\u0e08\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11\/10 \u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e44\u0e14\u0e49\u0e40\u0e23\u0e47\u0e27\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e43\u0e14<\/p>\n<p><a class=\"icon_down\" href=\"https:\/\/www.passele.com\/go\/win-password-recovery\" target=\"_blank\" rel=\"noopener\">\u0e25\u0e2d\u0e07\u0e1f\u0e23\u0e35<\/a><\/p>\n<p>\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e25\u0e37\u0e21\u0e14\u0e49\u0e27\u0e22 Windows Password Remover \u0e43\u0e2b\u0e49\u0e17\u0e33\u0e15\u0e32\u0e21\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07<\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 1. \u0e43\u0e0a\u0e49\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14 \u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e43\u0e0a\u0e49 Windows Password Remover<\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 2. \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e39\u0e15\u0e41\u0e25\u0e49\u0e27\u0e04\u0e25\u0e34\u0e01 <strong>\u0e16\u0e31\u0e14\u0e44\u0e1b<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14081\" src=\"https:\/\/www.passele.com\/images\/pp-w-cd-usb.png\" alt=\"\u0e15\u0e31\u0e27\u0e25\u0e1a\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows\" width=\"1119\" height=\"687\" srcset=\"https:\/\/www.passele.com\/images\/pp-w-cd-usb.png 1119w, https:\/\/www.passele.com\/images\/pp-w-cd-usb-300x184.png 300w, https:\/\/www.passele.com\/images\/pp-w-cd-usb-1024x629.png 1024w, https:\/\/www.passele.com\/images\/pp-w-cd-usb-768x472.png 768w\" sizes=\"auto, (max-width: 1119px) 100vw, 1119px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 3 \u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e16\u0e31\u0e14\u0e44\u0e1b \u0e04\u0e25\u0e34\u0e01 <strong>\u0e16\u0e31\u0e14\u0e44\u0e1b<\/strong> \u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e0b\u0e35\u0e14\u0e35 \u0e14\u0e35\u0e27\u0e35\u0e14\u0e35 \u0e2b\u0e23\u0e37\u0e2d USB \u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e08\u0e30\u0e16\u0e39\u0e01\u0e40\u0e02\u0e35\u0e22\u0e19<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14126\" src=\"https:\/\/www.passele.com\/images\/pp-w-select-cd-usb-brand.jpeg\" alt=\"\u0e40\u0e1a\u0e34\u0e23\u0e4c\u0e19 USB, CD \u0e2b\u0e23\u0e37\u0e2d DVD \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1a\u0e39\u0e4a\u0e15\u0e44\u0e14\u0e49\" width=\"1119\" height=\"690\" srcset=\"https:\/\/www.passele.com\/images\/pp-w-select-cd-usb-brand.jpeg 1119w, https:\/\/www.passele.com\/images\/pp-w-select-cd-usb-brand-300x185.jpeg 300w, https:\/\/www.passele.com\/images\/pp-w-select-cd-usb-brand-1024x631.jpeg 1024w, https:\/\/www.passele.com\/images\/pp-w-select-cd-usb-brand-768x474.jpeg 768w\" sizes=\"auto, (max-width: 1119px) 100vw, 1119px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 4 \u0e43\u0e2a\u0e48 USB, CD \u0e2b\u0e23\u0e37\u0e2d DVD \u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1a\u0e39\u0e4a\u0e15\u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e41\u0e25\u0e47\u0e1b\u0e17\u0e47\u0e2d\u0e1b\u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e25\u0e37\u0e21<\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 5 \u0e23\u0e35\u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e17\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e14 <strong>&#8220;F12&#8221;<\/strong> \u0e2b\u0e23\u0e37\u0e2d <strong>&#8220;ESC&#8221;<\/strong><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 6 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e04\u0e38\u0e13\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e40\u0e21\u0e19\u0e39 Boot \u0e43\u0e2b\u0e49\u0e04\u0e49\u0e19\u0e2b\u0e32\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e2a\u0e48\u0e44\u0e27\u0e49\u0e08\u0e32\u0e01\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e01\u0e32\u0e23\u0e1a\u0e39\u0e15 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e41\u0e25\u0e49\u0e27\u0e01\u0e14 <strong>Enter<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13806\" src=\"https:\/\/www.passele.com\/images\/e-passfab-4winkey-boot-from-usb-uefi.jpg\" alt=\"passfab 4winkey \u0e1a\u0e39\u0e15\u0e08\u0e32\u0e01 usb uefi\" width=\"640\" height=\"480\" srcset=\"https:\/\/www.passele.com\/images\/e-passfab-4winkey-boot-from-usb-uefi.jpg 640w, https:\/\/www.passele.com\/images\/e-passfab-4winkey-boot-from-usb-uefi-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 7 \u0e17\u0e35\u0e48\u0e19\u0e35\u0e48 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e08\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07 \u0e17\u0e35\u0e48\u0e19\u0e35\u0e48 \u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e41\u0e25\u0e30\u0e04\u0e25\u0e34\u0e01 <strong>\u0e16\u0e31\u0e14\u0e44\u0e1b<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14104\" src=\"https:\/\/www.passele.com\/images\/pp-w-choose-system.jpeg\" alt=\"\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 Windows \u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e25\u0e1a\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\" width=\"1120\" height=\"690\" srcset=\"https:\/\/www.passele.com\/images\/pp-w-choose-system.jpeg 1120w, https:\/\/www.passele.com\/images\/pp-w-choose-system-300x185.jpeg 300w, https:\/\/www.passele.com\/images\/pp-w-choose-system-1024x631.jpeg 1024w, https:\/\/www.passele.com\/images\/pp-w-choose-system-768x473.jpeg 768w\" sizes=\"auto, (max-width: 1120px) 100vw, 1120px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 8 \u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e1c\u0e39\u0e49\u0e14\u0e39\u0e41\u0e25\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e25\u0e37\u0e2d\u0e01 <strong>\u201c\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows\u201d<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14087\" src=\"https:\/\/www.passele.com\/images\/pp-w-choose-a-task.jpeg\" alt=\"\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e41\u0e17\u0e04\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a windows\" width=\"1120\" height=\"690\" srcset=\"https:\/\/www.passele.com\/images\/pp-w-choose-a-task.jpeg 1120w, https:\/\/www.passele.com\/images\/pp-w-choose-a-task-300x185.jpeg 300w, https:\/\/www.passele.com\/images\/pp-w-choose-a-task-1024x631.jpeg 1024w, https:\/\/www.passele.com\/images\/pp-w-choose-a-task-768x473.jpeg 768w\" sizes=\"auto, (max-width: 1120px) 100vw, 1120px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 9 \u0e43\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e16\u0e31\u0e14\u0e44\u0e1b \u0e43\u0e2b\u0e49\u0e43\u0e2a\u0e48\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e04\u0e25\u0e34\u0e01 <strong>\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14123\" src=\"https:\/\/www.passele.com\/images\/pp-w-reset-password-windows.jpeg\" alt=\"\u0e1b\u0e49\u0e2d\u0e19\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 windows \u0e43\u0e2b\u0e21\u0e48\" width=\"1120\" height=\"690\" srcset=\"https:\/\/www.passele.com\/images\/pp-w-reset-password-windows.jpeg 1120w, https:\/\/www.passele.com\/images\/pp-w-reset-password-windows-300x185.jpeg 300w, https:\/\/www.passele.com\/images\/pp-w-reset-password-windows-1024x631.jpeg 1024w, https:\/\/www.passele.com\/images\/pp-w-reset-password-windows-768x473.jpeg 768w\" sizes=\"auto, (max-width: 1120px) 100vw, 1120px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 10 \u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e08\u0e30\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e35\u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e17\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e14\u0e49\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11\/10 \u0e41\u0e25\u0e49\u0e27<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14138\" src=\"https:\/\/www.passele.com\/images\/pp-w-successfully-reset-password.jpeg\" alt=\"\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 windows\" width=\"1120\" height=\"690\" srcset=\"https:\/\/www.passele.com\/images\/pp-w-successfully-reset-password.jpeg 1120w, https:\/\/www.passele.com\/images\/pp-w-successfully-reset-password-300x185.jpeg 300w, https:\/\/www.passele.com\/images\/pp-w-successfully-reset-password-1024x631.jpeg 1024w, https:\/\/www.passele.com\/images\/pp-w-successfully-reset-password-768x473.jpeg 768w\" sizes=\"auto, (max-width: 1120px) 100vw, 1120px\" \/><\/p>\n<p><a class=\"icon_down\" href=\"https:\/\/www.passele.com\/go\/win-password-recovery\" target=\"_blank\" rel=\"noopener\">\u0e25\u0e2d\u0e07\u0e1f\u0e23\u0e35<\/a><\/p>\n<h3>\u0e27\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48 2 \u0e27\u0e34\u0e18\u0e35\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e25\u0e37\u0e21\u0e14\u0e49\u0e27\u0e22\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19<\/h3>\n<p>\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49 Password Reset Disk \u0e44\u0e14\u0e49\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e25\u0e37\u0e21\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e1c\u0e39\u0e49\u0e14\u0e39\u0e41\u0e25\u0e23\u0e30\u0e1a\u0e1a Windows \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e27\u0e34\u0e18\u0e35\u0e19\u0e35\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e04\u0e38\u0e13\u0e44\u0e14\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e44\u0e27\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e25\u0e37\u0e21\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 \u0e04\u0e38\u0e13\u0e08\u0e30\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e44\u0e14\u0e49\u0e43\u0e19\u0e02\u0e13\u0e30\u0e19\u0e35\u0e49 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01 Windows 11 \u0e16\u0e39\u0e01\u0e25\u0e47\u0e2d\u0e01\u0e44\u0e27\u0e49<\/p>\n<p>\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e40\u0e04\u0e22\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e19 \u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e27\u0e34\u0e18\u0e35\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e17\u0e38\u0e01\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e25\u0e37\u0e21\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e1c\u0e39\u0e49\u0e14\u0e39\u0e41\u0e25\u0e23\u0e30\u0e1a\u0e1a Windows 11 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e19\u0e35\u0e49 \u0e43\u0e2b\u0e49\u0e17\u0e33\u0e15\u0e32\u0e21\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07<\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 1. \u0e40\u0e2a\u0e35\u0e22\u0e1a\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13 \u0e17\u0e35\u0e48\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e23\u0e30\u0e1a\u0e1a \u0e43\u0e2b\u0e49\u0e25\u0e2d\u0e07\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e04\u0e38\u0e13\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e25\u0e34\u0e07\u0e01\u0e4c <strong>&#8220;\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19&#8221;<\/strong> \u0e43\u0e15\u0e49\u0e0a\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e23\u0e30\u0e1a\u0e1a<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14627\" src=\"https:\/\/www.passele.com\/images\/e-reset-password-link-in-windows-10.jpg\" alt=\"\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e25\u0e34\u0e07\u0e01\u0e4c\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e43\u0e19 windows 10\" width=\"600\" height=\"450\" srcset=\"https:\/\/www.passele.com\/images\/e-reset-password-link-in-windows-10.jpg 600w, https:\/\/www.passele.com\/images\/e-reset-password-link-in-windows-10-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 2. \u0e04\u0e25\u0e34\u0e01\u0e25\u0e34\u0e07\u0e01\u0e4c <strong>&#8220;\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19&#8221;<\/strong> \u0e41\u0e25\u0e30\u0e27\u0e34\u0e0b\u0e32\u0e23\u0e4c\u0e14\u0e01\u0e32\u0e23\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e08\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e04\u0e25\u0e34\u0e01 <strong>\u0e16\u0e31\u0e14\u0e44\u0e1b<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14323\" src=\"https:\/\/www.passele.com\/images\/e-password-reset-wizard.jpg\" alt=\"\u0e27\u0e34\u0e0b\u0e32\u0e23\u0e4c\u0e14\u0e01\u0e32\u0e23\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\" width=\"505\" height=\"393\" srcset=\"https:\/\/www.passele.com\/images\/e-password-reset-wizard.jpg 505w, https:\/\/www.passele.com\/images\/e-password-reset-wizard-300x233.jpg 300w\" sizes=\"auto, (max-width: 505px) 100vw, 505px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 3 \u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e34\u0e01 <strong>\u0e16\u0e31\u0e14\u0e44\u0e1b<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14326\" src=\"https:\/\/www.passele.com\/images\/e-insert-the-password-reset-disk.jpg\" alt=\"\u0e43\u0e2a\u0e48\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\" width=\"498\" height=\"391\" srcset=\"https:\/\/www.passele.com\/images\/e-insert-the-password-reset-disk.jpg 498w, https:\/\/www.passele.com\/images\/e-insert-the-password-reset-disk-300x236.jpg 300w\" sizes=\"auto, (max-width: 498px) 100vw, 498px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 4 \u0e43\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e16\u0e31\u0e14\u0e44\u0e1b \u0e43\u0e2b\u0e49\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e04\u0e33\u0e43\u0e1a\u0e49\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e25\u0e49\u0e27\u0e04\u0e25\u0e34\u0e01 <strong>\u0e16\u0e31\u0e14\u0e44\u0e1b<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14329\" src=\"https:\/\/www.passele.com\/images\/e-type-new-password-in-password-reset-wizard.jpg\" alt=\"\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e19\u0e27\u0e34\u0e0b\u0e32\u0e23\u0e4c\u0e14\u0e01\u0e32\u0e23\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\" width=\"500\" height=\"386\" srcset=\"https:\/\/www.passele.com\/images\/e-type-new-password-in-password-reset-wizard.jpg 800w, https:\/\/www.passele.com\/images\/e-type-new-password-in-password-reset-wizard-300x232.jpg 300w, https:\/\/www.passele.com\/images\/e-type-new-password-in-password-reset-wizard-768x593.jpg 768w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 5 \u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e08\u0e30\u0e16\u0e39\u0e01\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15 \u0e2b\u0e32\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e34\u0e14\u0e27\u0e34\u0e0b\u0e32\u0e23\u0e4c\u0e14 \u0e43\u0e2b\u0e49\u0e04\u0e25\u0e34\u0e01 <strong>\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e2a\u0e34\u0e49\u0e19<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14332\" src=\"https:\/\/www.passele.com\/images\/e-complete-password-reset-wizard.jpg\" alt=\"\u0e15\u0e31\u0e27\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e32\u0e23\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\" width=\"499\" height=\"393\" srcset=\"https:\/\/www.passele.com\/images\/e-complete-password-reset-wizard.jpg 499w, https:\/\/www.passele.com\/images\/e-complete-password-reset-wizard-300x236.jpg 300w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/><\/p>\n<h3>\u0e27\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48 3 \u0e27\u0e34\u0e18\u0e35\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e25\u0e37\u0e21\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e1a\u0e31\u0e0d\u0e0a\u0e35 Microsoft<\/h3>\n<p>\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e1a\u0e31\u0e0d\u0e0a\u0e35 Microsoft \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e23\u0e30\u0e1a\u0e1a Windows 11 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e27\u0e34\u0e18\u0e35\u0e19\u0e35\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e2d\u0e37\u0e48\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e1a\u0e31\u0e0d\u0e0a\u0e35 Microsoft \u0e41\u0e25\u0e30\u0e2b\u0e32\u0e01\u0e44\u0e21\u0e48\u0e21\u0e35\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49 \u0e04\u0e38\u0e13\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e27\u0e34\u0e18\u0e35\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49 \u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e14\u0e49\u0e27\u0e22\u0e1a\u0e31\u0e0d\u0e0a\u0e35 Microsoft \u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13 \u0e43\u0e2b\u0e49\u0e17\u0e33\u0e15\u0e32\u0e21\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07<\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 1. \u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e41\u0e25\u0e30\u0e44\u0e1b\u0e17\u0e35\u0e48 https:\/\/account.live.com\/password\/reset<\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 2. \u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e04\u0e38\u0e13\u0e08\u0e30\u0e1e\u0e1a\u0e2a\u0e32\u0e21\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e04\u0e38\u0e13\u0e04\u0e27\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e41\u0e23\u0e01 \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e47\u0e04\u0e37\u0e2d <strong>\u201c\u0e09\u0e31\u0e19\u0e25\u0e37\u0e21\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u201d<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14732\" src=\"https:\/\/www.passele.com\/images\/e-microsoft-i-forgot-password-box-option-highlighted.jpg\" alt=\"microsoft \u0e09\u0e31\u0e19\u0e25\u0e37\u0e21\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e19\u0e49\u0e19\" width=\"600\" height=\"372\" srcset=\"https:\/\/www.passele.com\/images\/e-microsoft-i-forgot-password-box-option-highlighted.jpg 600w, https:\/\/www.passele.com\/images\/e-microsoft-i-forgot-password-box-option-highlighted-300x186.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 3 \u0e43\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e16\u0e31\u0e14\u0e44\u0e1b \u0e43\u0e2b\u0e49\u0e1b\u0e49\u0e2d\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35 Microsoft \u0e41\u0e25\u0e30\u0e2d\u0e31\u0e01\u0e02\u0e23\u0e30\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e40\u0e2b\u0e47\u0e19\u0e1a\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d \u0e41\u0e25\u0e49\u0e27\u0e04\u0e25\u0e34\u0e01 <strong>\u0e16\u0e31\u0e14\u0e44\u0e1b<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14739\" src=\"https:\/\/www.passele.com\/images\/e-enter-the-microsoft-account-and-characters.jpg\" alt=\"\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e1a\u0e31\u0e0d\u0e0a\u0e35 microsoft \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e2d\u0e31\u0e01\u0e29\u0e23\" width=\"602\" height=\"666\" srcset=\"https:\/\/www.passele.com\/images\/e-enter-the-microsoft-account-and-characters.jpg 602w, https:\/\/www.passele.com\/images\/e-enter-the-microsoft-account-and-characters-271x300.jpg 271w\" sizes=\"auto, (max-width: 602px) 100vw, 602px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e31\u0e14\u0e44\u0e1b \u0e04\u0e38\u0e13\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e31\u0e1a\u0e23\u0e2b\u0e31\u0e2a\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e44\u0e14\u0e49 \u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19 ID \u0e2d\u0e35\u0e40\u0e21\u0e25\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c \u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e04\u0e38\u0e13\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e2b\u0e31\u0e2a<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14745\" src=\"https:\/\/www.passele.com\/images\/e-select-where-you-want-to-receive-a-code-for-microsoft.jpg\" alt=\"\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2b\u0e31\u0e2a\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a microsoft\" width=\"537\" height=\"585\" srcset=\"https:\/\/www.passele.com\/images\/e-select-where-you-want-to-receive-a-code-for-microsoft.jpg 537w, https:\/\/www.passele.com\/images\/e-select-where-you-want-to-receive-a-code-for-microsoft-275x300.jpg 275w\" sizes=\"auto, (max-width: 537px) 100vw, 537px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 5 \u0e1b\u0e49\u0e2d\u0e19\u0e23\u0e2b\u0e31\u0e2a\u0e43\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e16\u0e31\u0e14\u0e44\u0e1b \u0e1b\u0e49\u0e2d\u0e19\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e44\u0e14\u0e49<\/p>\n<p>\u0e43\u0e19\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e23\u0e2b\u0e31\u0e2a\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e2a\u0e33\u0e23\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e4c\u0e43\u0e2b\u0e49\u0e43\u0e2a\u0e48\u0e23\u0e2b\u0e31\u0e2a \u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e27\u0e48\u0e32\u0e09\u0e31\u0e19\u0e44\u0e21\u0e48\u0e21\u0e35\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49 \u0e16\u0e31\u0e14\u0e44\u0e1b \u0e04\u0e38\u0e13\u0e08\u0e30\u0e16\u0e39\u0e01\u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e1b\u0e49\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2b\u0e31\u0e2a\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e04\u0e38\u0e13\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e1b\u0e49\u0e2d\u0e19\u0e2d\u0e31\u0e01\u0e02\u0e23\u0e30\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e40\u0e2b\u0e47\u0e19\u0e1a\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e01\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e34\u0e01 <strong>\u0e16\u0e31\u0e14\u0e44\u0e1b<\/strong> \u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49 \u0e43\u0e2b\u0e49\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e23\u0e2b\u0e31\u0e2a\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e1b\u0e49\u0e2d\u0e19\u0e43\u0e19\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32 \u0e04\u0e38\u0e13\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e2b\u0e31\u0e2a\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35 Microsoft \u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13 \u0e1b\u0e49\u0e2d\u0e19\u0e23\u0e2b\u0e31\u0e2a\u0e19\u0e35\u0e49\u0e43\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e23\u0e2d\u0e01\u0e41\u0e25\u0e30\u0e04\u0e25\u0e34\u0e01 <strong>\u0e22\u0e37\u0e19\u0e22\u0e31\u0e19<\/strong> \u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49 \u0e2b\u0e19\u0e49\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e04\u0e38\u0e13\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e2d\u0e1a\u0e04\u0e33\u0e16\u0e32\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13 \u0e15\u0e2d\u0e1a\u0e04\u0e33\u0e16\u0e32\u0e21\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e35\u0e49\u0e41\u0e25\u0e30\u0e04\u0e25\u0e34\u0e01 <strong>\u0e16\u0e31\u0e14\u0e44\u0e1b<\/strong><\/p>\n<p>\u0e17\u0e35\u0e21 Microsoft \u0e08\u0e30\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e19\u0e35\u0e49 \u0e41\u0e25\u0e30\u0e2b\u0e32\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1e\u0e2d \u0e04\u0e38\u0e13\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13<\/p>\n<h3>\u0e27\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48 4 \u0e27\u0e34\u0e18\u0e35\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e25\u0e37\u0e21\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49 CMD<\/h3>\n<p>\u0e43\u0e19\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e25\u0e37\u0e21\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49 Command Prompt \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows \u0e44\u0e14\u0e49 \u0e27\u0e34\u0e18\u0e35\u0e19\u0e35\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c Windows 11 \u0e16\u0e39\u0e01\u0e25\u0e47\u0e2d\u0e04 \u0e2b\u0e32\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e27\u0e34\u0e18\u0e35\u0e19\u0e35\u0e49 \u0e04\u0e38\u0e13\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e41\u0e1c\u0e48\u0e19\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 Windows<\/p>\n<p>\u0e17\u0e33\u0e15\u0e32\u0e21\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e1e\u0e23\u0e2d\u0e21\u0e15\u0e4c\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07<\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 1. \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 Windows 11 \u0e43\u0e19\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e44\u0e21\u0e48\u0e21\u0e35\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 Windows 11 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e21\u0e31\u0e19\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e37\u0e48\u0e2d\u0e1a\u0e19\u0e1e\u0e35\u0e0b\u0e35\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e44\u0e14\u0e49 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e19\u0e35\u0e49 \u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14 Media Creation Tool \u0e08\u0e32\u0e01 https:\/\/www.microsoft.com\/en-in\/software-download\/Windows10 \u0e41\u0e25\u0e30\u0e40\u0e23\u0e35\u0e22\u0e01\u0e43\u0e0a\u0e49<\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 2. \u0e43\u0e2a\u0e48\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e25\u0e07\u0e43\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e25\u0e37\u0e21 \u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49 \u0e23\u0e35\u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e17\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e14\u0e1b\u0e38\u0e48\u0e21 Boot Option Key \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e19\u0e01\u0e27\u0e48\u0e32 Boot Options Menu \u0e08\u0e30\u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e02\u0e36\u0e49\u0e19\u0e1a\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d \u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48 \u0e40\u0e25\u0e37\u0e2d\u0e01 <strong>\u0e14\u0e34\u0e2a\u0e01\u0e4c USB<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14750\" src=\"https:\/\/www.passele.com\/images\/e-boot-option-menu-in-windows.jpg\" alt=\"\u0e40\u0e21\u0e19\u0e39\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e01\u0e32\u0e23\u0e1a\u0e39\u0e15\u0e43\u0e19 windows\" width=\"432\" height=\"134\" srcset=\"https:\/\/www.passele.com\/images\/e-boot-option-menu-in-windows.jpg 432w, https:\/\/www.passele.com\/images\/e-boot-option-menu-in-windows-300x93.jpg 300w\" sizes=\"auto, (max-width: 432px) 100vw, 432px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 3 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e23\u0e34\u0e48\u0e21\u0e17\u0e33\u0e07\u0e32\u0e19 \u0e04\u0e38\u0e13\u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32 Windows \u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e01\u0e14 <strong>Shift + F10<\/strong> \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e1e\u0e23\u0e2d\u0e21\u0e15\u0e4c\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e08\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14754\" src=\"https:\/\/www.passele.com\/images\/e-windows-10-command-prompt.jpg\" alt=\"\u0e1e\u0e23\u0e2d\u0e21\u0e15\u0e4c\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07 windows 10\" width=\"486\" height=\"212\" srcset=\"https:\/\/www.passele.com\/images\/e-windows-10-command-prompt.jpg 486w, https:\/\/www.passele.com\/images\/e-windows-10-command-prompt-300x131.jpg 300w\" sizes=\"auto, (max-width: 486px) 100vw, 486px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 4 \u0e16\u0e31\u0e14\u0e44\u0e1b \u0e40\u0e23\u0e35\u0e22\u0e01\u0e43\u0e0a\u0e49\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e41\u0e17\u0e19\u0e17\u0e35\u0e48\u0e15\u0e31\u0e27\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e22\u0e39\u0e17\u0e34\u0e25\u0e34\u0e15\u0e35\u0e49\u0e14\u0e49\u0e27\u0e22\u0e1e\u0e23\u0e2d\u0e21\u0e15\u0e4c\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07<\/p>\n<p><code>move d:\\Windows\\system32\\utilman.exe d:\\<br \/>\ncopy d:\\Windows\\system32\\cmd.exe d:\\Windows\\system32\\utilman.exe<\/code><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14757\" src=\"https:\/\/www.passele.com\/images\/e-run-the-command-to-reset-windows-password.jpg\" alt=\"\u0e40\u0e23\u0e35\u0e22\u0e01\u0e43\u0e0a\u0e49\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 windows\" width=\"660\" height=\"195\" srcset=\"https:\/\/www.passele.com\/images\/e-run-the-command-to-reset-windows-password.jpg 660w, https:\/\/www.passele.com\/images\/e-run-the-command-to-reset-windows-password-300x89.jpg 300w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 5 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27 \u0e43\u0e2b\u0e49\u0e23\u0e35\u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e17\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e16\u0e2d\u0e14\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e2d\u0e01<\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 6 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e23\u0e35\u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e17\u0e41\u0e25\u0e30\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e25\u0e07\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e43\u0e0a\u0e49\u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e02\u0e36\u0e49\u0e19 \u0e43\u0e2b\u0e49\u0e04\u0e25\u0e34\u0e01\u0e17\u0e35\u0e48\u0e44\u0e2d\u0e04\u0e2d\u0e19 <strong>Ease of Access<\/strong> \u0e16\u0e31\u0e14\u0e08\u0e32\u0e01\u0e1b\u0e38\u0e48\u0e21 <strong>Power<\/strong> \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e1e\u0e23\u0e2d\u0e21\u0e15\u0e4c\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e1a\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14760\" src=\"https:\/\/www.passele.com\/images\/e-command-prompt-on-windows-10.jpg\" alt=\"\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e1a\u0e19 windows 10\" width=\"660\" height=\"357\" srcset=\"https:\/\/www.passele.com\/images\/e-command-prompt-on-windows-10.jpg 660w, https:\/\/www.passele.com\/images\/e-command-prompt-on-windows-10-300x162.jpg 300w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 7 \u0e17\u0e35\u0e48\u0e19\u0e35\u0e48 \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19:<code>net user {username} {password}<\/code> \u0e41\u0e25\u0e30\u0e01\u0e14 <strong>Enter<\/strong> \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49\u0e08\u0e30\u0e15\u0e31\u0e49\u0e07\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e1c\u0e39\u0e49\u0e14\u0e39\u0e41\u0e25\u0e23\u0e30\u0e1a\u0e1a\u0e20\u0e32\u0e22\u0e43\u0e19\u0e02\u0e2d\u0e07 Windows 11 \u0e43\u0e2b\u0e21\u0e48<\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 8 \u0e16\u0e31\u0e14\u0e44\u0e1b \u0e1b\u0e34\u0e14\u0e1e\u0e23\u0e2d\u0e21\u0e15\u0e4c\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07 \u0e41\u0e25\u0e30\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e25\u0e07\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e43\u0e0a\u0e49\u0e14\u0e49\u0e27\u0e22\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e43\u0e2b\u0e21\u0e48<\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 9 \u0e43\u0e2a\u0e48\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e25\u0e07\u0e43\u0e19\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c Windows 11 \u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07 \u0e04\u0e25\u0e34\u0e01\u0e17\u0e35\u0e48\u0e44\u0e2d\u0e04\u0e2d\u0e19 <strong>Power<\/strong> \u0e41\u0e25\u0e49\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01 <strong>Restart<\/strong><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 10 \u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e08\u0e30\u0e1a\u0e39\u0e4a\u0e15 \u0e04\u0e38\u0e13\u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32 Windows \u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e01\u0e14 <strong>Shift + F10<\/strong> \u0e41\u0e25\u0e30\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07\u0e1e\u0e23\u0e2d\u0e21\u0e15\u0e4c\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e08\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19<\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 11 \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07<code>copy d:\\utilman.exe d:\\Windows\\system32\\utilman.exe<\/code> . \u0e01\u0e14 <strong>Enter<\/strong> \u0e41\u0e25\u0e30\u0e1e\u0e34\u0e21\u0e1e\u0e4c<code>Yes<\/code> \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e37\u0e19\u0e04\u0e48\u0e32 Utility Manager<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14763\" src=\"https:\/\/www.passele.com\/images\/e-type-command-in-windows-10.jpg\" alt=\"e \u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07\u0e43\u0e19 windows 10\" width=\"600\" height=\"237\" srcset=\"https:\/\/www.passele.com\/images\/e-type-command-in-windows-10.jpg 600w, https:\/\/www.passele.com\/images\/e-type-command-in-windows-10-300x119.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 12 \u0e16\u0e31\u0e14\u0e44\u0e1b \u0e1b\u0e34\u0e14\u0e1e\u0e23\u0e2d\u0e21\u0e15\u0e4c\u0e04\u0e33\u0e2a\u0e31\u0e48\u0e07 \u0e19\u0e33\u0e14\u0e34\u0e2a\u0e01\u0e4c\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07 Windows 11 \u0e2d\u0e2d\u0e01\u0e01\u0e48\u0e2d\u0e19\u0e23\u0e35\u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e17\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c<\/p>\n<p>\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e25\u0e07\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e43\u0e0a\u0e49 Windows 11 \u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08<\/p>\n<h3>\u0e27\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48 5. \u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e48\u0e32\u0e08\u0e32\u0e01\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e25\u0e37\u0e21<\/h3>\n<p>\u0e43\u0e19\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e25\u0e37\u0e21\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e1c\u0e39\u0e49\u0e14\u0e39\u0e41\u0e25\u0e23\u0e30\u0e1a\u0e1a Windows 11 \u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e1e\u0e35\u0e0b\u0e35\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32\u0e08\u0e32\u0e01\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49\u0e08\u0e30\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e17\u0e35\u0e48\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e44\u0e27\u0e49\u0e43\u0e19\u0e2e\u0e32\u0e23\u0e4c\u0e14\u0e44\u0e14\u0e23\u0e1f\u0e4c\u0e02\u0e2d\u0e07\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e2a\u0e39\u0e0d\u0e2b\u0e32\u0e22<\/p>\n<p>\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e48\u0e32\u0e08\u0e32\u0e01\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19 \u0e43\u0e2b\u0e49\u0e17\u0e33\u0e15\u0e32\u0e21\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e23\u0e30\u0e1a\u0e38\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07:<\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 1. \u0e44\u0e1b\u0e17\u0e35\u0e48\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e23\u0e30\u0e1a\u0e1a Windows<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14766\" src=\"https:\/\/www.passele.com\/images\/e-windows-login-screen.jpg\" alt=\"\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e23\u0e30\u0e1a\u0e1a windows\" width=\"1023\" height=\"562\" srcset=\"https:\/\/www.passele.com\/images\/e-windows-login-screen.jpg 1023w, https:\/\/www.passele.com\/images\/e-windows-login-screen-300x165.jpg 300w, https:\/\/www.passele.com\/images\/e-windows-login-screen-768x422.jpg 768w\" sizes=\"auto, (max-width: 1023px) 100vw, 1023px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 2. \u0e17\u0e35\u0e48\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07\u0e02\u0e27\u0e32\u0e02\u0e2d\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d \u0e04\u0e38\u0e13\u0e08\u0e30\u0e1e\u0e1a\u0e44\u0e2d\u0e04\u0e2d\u0e19 <strong>\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19<\/strong> \u0e04\u0e25\u0e34\u0e01\u0e17\u0e35\u0e48\u0e44\u0e2d\u0e04\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e41\u0e25\u0e30\u0e40\u0e25\u0e37\u0e2d\u0e01 <strong>\u0e23\u0e35\u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e17<\/strong> \u0e41\u0e25\u0e30\u0e43\u0e19\u0e02\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e43\u0e2b\u0e49\u0e01\u0e14\u0e1b\u0e38\u0e48\u0e21 <strong>&#8220;Shift&#8221;<\/strong> \u0e1a\u0e19\u0e41\u0e1b\u0e49\u0e19\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e15\u0e48\u0e2d\u0e44\u0e1b<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14311\" src=\"https:\/\/www.passele.com\/images\/e-click-restart-and-press-shift-key-in-windows.jpg\" alt=\"\u0e04\u0e25\u0e34\u0e01\u0e23\u0e35\u0e2a\u0e15\u0e32\u0e23\u0e4c\u0e17\u0e41\u0e25\u0e49\u0e27\u0e01\u0e14\u0e1b\u0e38\u0e48\u0e21 shift \u0e43\u0e19 windows\" width=\"494\" height=\"264\" srcset=\"https:\/\/www.passele.com\/images\/e-click-restart-and-press-shift-key-in-windows.jpg 494w, https:\/\/www.passele.com\/images\/e-click-restart-and-press-shift-key-in-windows-300x160.jpg 300w\" sizes=\"auto, (max-width: 494px) 100vw, 494px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 3 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49 Windows 11 \u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e35\u0e1a\u0e39\u0e15 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e23\u0e30\u0e1a\u0e1a\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e08\u0e30\u0e44\u0e21\u0e48\u0e42\u0e2b\u0e25\u0e14\u0e15\u0e32\u0e21\u0e1b\u0e01\u0e15\u0e34 \u0e41\u0e25\u0e30\u0e04\u0e38\u0e13\u0e08\u0e30\u0e1e\u0e1a\u0e40\u0e21\u0e19\u0e39\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e01\u0e32\u0e23\u0e1a\u0e39\u0e15 \u0e17\u0e35\u0e48\u0e19\u0e35\u0e48 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01 <strong>\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32<\/strong> \u0e41\u0e25\u0e49\u0e27\u0e01\u0e14 <strong>Enter<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14314\" src=\"https:\/\/www.passele.com\/images\/e-choose-an-option-troubleshoot.jpg\" alt=\"\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01 \u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\" width=\"644\" height=\"476\" srcset=\"https:\/\/www.passele.com\/images\/e-choose-an-option-troubleshoot.jpg 644w, https:\/\/www.passele.com\/images\/e-choose-an-option-troubleshoot-300x222.jpg 300w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 4 \u0e08\u0e32\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e16\u0e31\u0e14\u0e44\u0e1b \u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01 <strong>\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e1e\u0e35\u0e0b\u0e35\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e19\u0e35\u0e49<\/strong> \u0e41\u0e25\u0e49\u0e27\u0e01\u0e14 <strong>Enter<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13796\" src=\"https:\/\/www.passele.com\/images\/e-reset-your-pc-in-troubleshoot.jpg\" alt=\"\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e1e\u0e35\u0e0b\u0e35\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\" width=\"800\" height=\"718\" srcset=\"https:\/\/www.passele.com\/images\/e-reset-your-pc-in-troubleshoot.jpg 800w, https:\/\/www.passele.com\/images\/e-reset-your-pc-in-troubleshoot-300x269.jpg 300w, https:\/\/www.passele.com\/images\/e-reset-your-pc-in-troubleshoot-768x689.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 5 \u0e08\u0e32\u0e01\u0e2b\u0e19\u0e49\u0e32\u0e08\u0e2d\u0e16\u0e31\u0e14\u0e44\u0e1b \u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01 <strong>&#8220;\u0e25\u0e1a\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07&#8221;<\/strong> \u0e42\u0e1b\u0e23\u0e14\u0e08\u0e33\u0e44\u0e27\u0e49\u0e27\u0e48\u0e32 \u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01 Keep my files \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e31\u0e19\u0e17\u0e36\u0e01\u0e44\u0e1f\u0e25\u0e4c \u0e23\u0e30\u0e1a\u0e1a\u0e08\u0e30\u0e16\u0e32\u0e21\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13 \u0e0b\u0e36\u0e48\u0e07\u0e04\u0e38\u0e13\u0e44\u0e21\u0e48\u0e21\u0e35 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32\u0e16\u0e49\u0e32\u0e40\u0e25\u0e37\u0e2d\u0e01 <strong>&#8220;Remove Everything&#8221;<\/strong> \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49\u0e08\u0e30\u0e25\u0e1a\u0e44\u0e1f\u0e25\u0e4c\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14320\" src=\"https:\/\/www.passele.com\/images\/e-remove-everything-highlighted.jpg\" alt=\"\u0e25\u0e1a\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e40\u0e19\u0e49\u0e19\" width=\"600\" height=\"406\" srcset=\"https:\/\/www.passele.com\/images\/e-remove-everything-highlighted.jpg 600w, https:\/\/www.passele.com\/images\/e-remove-everything-highlighted-300x203.jpg 300w, https:\/\/www.passele.com\/images\/e-remove-everything-highlighted-220x150.jpg 220w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 6 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e17\u0e33\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e41\u0e25\u0e49\u0e27 \u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e08\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e23\u0e35\u0e1a\u0e39\u0e15 \u0e41\u0e25\u0e30\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19 \u0e04\u0e38\u0e13\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e1e\u0e35\u0e0b\u0e35 \u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e15\u0e31\u0e27\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14769\" src=\"https:\/\/www.passele.com\/images\/e-do-you-want-to-clean-the-drives.jpg\" alt=\"\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e08\u0e30\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e44\u0e14\u0e23\u0e1f\u0e4c\" width=\"650\" height=\"344\" srcset=\"https:\/\/www.passele.com\/images\/e-do-you-want-to-clean-the-drives.jpg 650w, https:\/\/www.passele.com\/images\/e-do-you-want-to-clean-the-drives-300x159.jpg 300w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/p>\n<p>\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e04\u0e38\u0e13\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e31\u0e49\u0e07\u0e04\u0e48\u0e32\u0e1e\u0e35\u0e0b\u0e35 Windows 11 \u0e14\u0e49\u0e27\u0e22\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e1c\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e43\u0e2b\u0e21\u0e48<\/p>\n<h3>\u0e1a\u0e17\u0e2a\u0e23\u0e38\u0e1b<\/h3>\n<p>\u0e43\u0e19\u0e17\u0e49\u0e32\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e2d\u0e32\u0e08\u0e01\u0e25\u0e48\u0e32\u0e27\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e43\u0e2b\u0e0d\u0e48\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13 <strong>\u0e25\u0e37\u0e21\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e1c\u0e39\u0e49\u0e14\u0e39\u0e41\u0e25\u0e23\u0e30\u0e1a\u0e1a Windows 11\/10 \u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13<\/strong> \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11\/10 \u0e44\u0e14\u0e49 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e43\u0e14\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e07\u0e48\u0e32\u0e22\u0e40\u0e17\u0e48\u0e32\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49 <a href=\"https:\/\/www.passele.com\/go\/win-password-recovery\" target=\"_blank\" rel=\"noopener\">Windows Password Remover<\/a> \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e18\u0e35\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e15\u0e25\u0e32\u0e14 \u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e18\u0e35\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e0b\u0e36\u0e48\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e30\u0e14\u0e27\u0e01<\/p>\n<p><a class=\"icon_down\" href=\"https:\/\/www.passele.com\/go\/win-password-recovery\" target=\"_blank\" rel=\"noopener\">\u0e25\u0e2d\u0e07\u0e1f\u0e23\u0e35<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e2a\u0e34\u0e48\u0e07\u0e19\u0e35\u0e49\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e01\u0e31\u0e1a\u0e1e\u0e27\u0e01\u0e40\u0e23\u0e32\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19! \u0e04\u0e38\u0e13\u0e19\u0e31\u0e48\u0e07\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e25\u0e07\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e02 &hellip;<\/p>\n","protected":false},"author":1,"featured_media":14781,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[188],"tags":[],"class_list":["post-27411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category--windows"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e27\u0e34\u0e18\u0e35\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e25\u0e37\u0e21 - Passele<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.passele.com\/\u0e27\u0e34\u0e18\u0e35\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19-windows-11-\u0e17\u0e35\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e27\u0e34\u0e18\u0e35\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e25\u0e37\u0e21 - Passele\" \/>\n<meta property=\"og:description\" content=\"\u0e2a\u0e34\u0e48\u0e07\u0e19\u0e35\u0e49\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e01\u0e31\u0e1a\u0e1e\u0e27\u0e01\u0e40\u0e23\u0e32\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19! \u0e04\u0e38\u0e13\u0e19\u0e31\u0e48\u0e07\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e25\u0e07\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e02 &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.passele.com\/\u0e27\u0e34\u0e18\u0e35\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19-windows-11-\u0e17\u0e35\/\" \/>\n<meta property=\"og:site_name\" content=\"Passele\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-10T09:29:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.passele.com\/images\/pp-w-cd-usb.png\" \/>\n<meta name=\"author\" content=\"passele\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"passele\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/\"},\"author\":{\"name\":\"passele\",\"@id\":\"https:\/\/www.passele.com\/#\/schema\/person\/3c50a7f737f670621dd213413f208e23\"},\"headline\":\"\u0e27\u0e34\u0e18\u0e35\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e25\u0e37\u0e21\",\"datePublished\":\"2022-06-10T09:29:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/\"},\"wordCount\":126,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.passele.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.passele.com\/images\/e-reset-forgotten-windows-11-password.jpeg\",\"articleSection\":[\"\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e25\u0e1a\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows\"],\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/\",\"url\":\"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/\",\"name\":\"\u0e27\u0e34\u0e18\u0e35\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e25\u0e37\u0e21 - Passele\",\"isPartOf\":{\"@id\":\"https:\/\/www.passele.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.passele.com\/images\/e-reset-forgotten-windows-11-password.jpeg\",\"datePublished\":\"2022-06-10T09:29:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/#primaryimage\",\"url\":\"https:\/\/www.passele.com\/images\/e-reset-forgotten-windows-11-password.jpeg\",\"contentUrl\":\"https:\/\/www.passele.com\/images\/e-reset-forgotten-windows-11-password.jpeg\",\"width\":702,\"height\":392,\"caption\":\"\u0e27\u0e34\u0e18\u0e35\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e25\u0e37\u0e21\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9801\",\"item\":\"https:\/\/www.passele.com\/th\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e27\u0e34\u0e18\u0e35\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e25\u0e37\u0e21\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.passele.com\/#website\",\"url\":\"https:\/\/www.passele.com\/\",\"name\":\"Passele\",\"description\":\"Powerful and Professional File Password Removal Tools\",\"publisher\":{\"@id\":\"https:\/\/www.passele.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.passele.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.passele.com\/#organization\",\"name\":\"Passele\",\"url\":\"https:\/\/www.passele.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.passele.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.passele.com\/images\/passele-icon.png\",\"contentUrl\":\"https:\/\/www.passele.com\/images\/passele-icon.png\",\"width\":64,\"height\":64,\"caption\":\"Passele\"},\"image\":{\"@id\":\"https:\/\/www.passele.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.passele.com\/#\/schema\/person\/3c50a7f737f670621dd213413f208e23\",\"name\":\"passele\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.passele.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5cc03c8eb53d7e1798440133fcba4f59?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5cc03c8eb53d7e1798440133fcba4f59?s=96&d=mm&r=g\",\"caption\":\"passele\"},\"url\":\"https:\/\/www.passele.com\/th\/author\/passele\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e27\u0e34\u0e18\u0e35\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e25\u0e37\u0e21 - Passele","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.passele.com\/\u0e27\u0e34\u0e18\u0e35\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19-windows-11-\u0e17\u0e35\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e27\u0e34\u0e18\u0e35\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e25\u0e37\u0e21 - Passele","og_description":"\u0e2a\u0e34\u0e48\u0e07\u0e19\u0e35\u0e49\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e01\u0e31\u0e1a\u0e1e\u0e27\u0e01\u0e40\u0e23\u0e32\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19! \u0e04\u0e38\u0e13\u0e19\u0e31\u0e48\u0e07\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e25\u0e07\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e02 &hellip;","og_url":"https:\/\/www.passele.com\/\u0e27\u0e34\u0e18\u0e35\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19-windows-11-\u0e17\u0e35\/","og_site_name":"Passele","article_published_time":"2022-06-10T09:29:09+00:00","og_image":[{"url":"https:\/\/www.passele.com\/images\/pp-w-cd-usb.png","type":"","width":"","height":""}],"author":"passele","twitter_card":"summary_large_image","twitter_misc":{"Written by":"passele","Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/#article","isPartOf":{"@id":"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/"},"author":{"name":"passele","@id":"https:\/\/www.passele.com\/#\/schema\/person\/3c50a7f737f670621dd213413f208e23"},"headline":"\u0e27\u0e34\u0e18\u0e35\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e25\u0e37\u0e21","datePublished":"2022-06-10T09:29:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/"},"wordCount":126,"commentCount":0,"publisher":{"@id":"https:\/\/www.passele.com\/#organization"},"image":{"@id":"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/#primaryimage"},"thumbnailUrl":"https:\/\/www.passele.com\/images\/e-reset-forgotten-windows-11-password.jpeg","articleSection":["\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e25\u0e1a\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows"],"inLanguage":"th","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/","url":"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/","name":"\u0e27\u0e34\u0e18\u0e35\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e25\u0e37\u0e21 - Passele","isPartOf":{"@id":"https:\/\/www.passele.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/#primaryimage"},"image":{"@id":"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/#primaryimage"},"thumbnailUrl":"https:\/\/www.passele.com\/images\/e-reset-forgotten-windows-11-password.jpeg","datePublished":"2022-06-10T09:29:09+00:00","breadcrumb":{"@id":"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/#primaryimage","url":"https:\/\/www.passele.com\/images\/e-reset-forgotten-windows-11-password.jpeg","contentUrl":"https:\/\/www.passele.com\/images\/e-reset-forgotten-windows-11-password.jpeg","width":702,"height":392,"caption":"\u0e27\u0e34\u0e18\u0e35\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e25\u0e37\u0e21"},{"@type":"BreadcrumbList","@id":"https:\/\/www.passele.com\/%e0%b8%a7%e0%b8%b4%e0%b8%98%e0%b8%b5%e0%b8%a3%e0%b8%b5%e0%b9%80%e0%b8%8b%e0%b9%87%e0%b8%95%e0%b8%a3%e0%b8%ab%e0%b8%b1%e0%b8%aa%e0%b8%9c%e0%b9%88%e0%b8%b2%e0%b8%99-windows-11-%e0%b8%97%e0%b8%b5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9801","item":"https:\/\/www.passele.com\/th\/"},{"@type":"ListItem","position":2,"name":"\u0e27\u0e34\u0e18\u0e35\u0e23\u0e35\u0e40\u0e0b\u0e47\u0e15\u0e23\u0e2b\u0e31\u0e2a\u0e1c\u0e48\u0e32\u0e19 Windows 11 \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e25\u0e37\u0e21"}]},{"@type":"WebSite","@id":"https:\/\/www.passele.com\/#website","url":"https:\/\/www.passele.com\/","name":"Passele","description":"Powerful and Professional File Password Removal Tools","publisher":{"@id":"https:\/\/www.passele.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.passele.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/www.passele.com\/#organization","name":"Passele","url":"https:\/\/www.passele.com\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.passele.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.passele.com\/images\/passele-icon.png","contentUrl":"https:\/\/www.passele.com\/images\/passele-icon.png","width":64,"height":64,"caption":"Passele"},"image":{"@id":"https:\/\/www.passele.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.passele.com\/#\/schema\/person\/3c50a7f737f670621dd213413f208e23","name":"passele","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.passele.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5cc03c8eb53d7e1798440133fcba4f59?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5cc03c8eb53d7e1798440133fcba4f59?s=96&d=mm&r=g","caption":"passele"},"url":"https:\/\/www.passele.com\/th\/author\/passele\/"}]}},"_links":{"self":[{"href":"https:\/\/www.passele.com\/th\/wp-json\/wp\/v2\/posts\/27411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.passele.com\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.passele.com\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.passele.com\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.passele.com\/th\/wp-json\/wp\/v2\/comments?post=27411"}],"version-history":[{"count":0,"href":"https:\/\/www.passele.com\/th\/wp-json\/wp\/v2\/posts\/27411\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.passele.com\/th\/wp-json\/wp\/v2\/media\/14781"}],"wp:attachment":[{"href":"https:\/\/www.passele.com\/th\/wp-json\/wp\/v2\/media?parent=27411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.passele.com\/th\/wp-json\/wp\/v2\/categories?post=27411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.passele.com\/th\/wp-json\/wp\/v2\/tags?post=27411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}